{"id":98732,"date":"2025-07-08T10:17:48","date_gmt":"2025-07-08T14:17:48","guid":{"rendered":"https:\/\/www.iaff.org\/news\/des-affilies-du-7e-district-soutiennent-les-pompiers-de-lidaho-apres-une-embuscade\/"},"modified":"2025-07-18T13:24:53","modified_gmt":"2025-07-18T17:24:53","slug":"des-affilies-du-7e-district-soutiennent-les-pompiers-de-lidaho-apres-une-embuscade","status":"publish","type":"news","link":"https:\/\/www.iaff.org\/fr-ca\/news\/des-affilies-du-7e-district-soutiennent-les-pompiers-de-lidaho-apres-une-embuscade\/","title":{"rendered":"Des affili\u00e9s du 7e district soutiennent les pompiers de l\u2019Idaho apr\u00e8s une embuscade"},"content":{"rendered":"<section\n\t class=\"page-blocks iaff-page-blocks align wp-block-acf-page-blocks\" id=\"page-blocks_block_892628e9e1a74de319dbc39476723bc9\">\n\t<div class=\"acf-innerblocks-container\">\n<div class=\"wp-block-paragraph \">\n<p>Dans le service d\u2019incendie, \u00ab Personne ne se bat seul \u00bb est plus qu\u2019une simple devise, c\u2019est un mode de vie.  <\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>Cet engagement a \u00e9t\u00e9 pleinement d\u00e9montr\u00e9 apr\u00e8s qu\u2019une embuscade a laiss\u00e9 Coeur d\u2019Alene, le chef de bataillon de la section locale 710 de l\u2019Idaho, John Morrison, et le chef de bataillon de la section locale 2856 de Kootenai, Frank Harwood, tu\u00e9s et le pompier-ing\u00e9nieur de la section locale 710, Dave Tysdal, bless\u00e9.  <\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>Pr\u00e8s de 80 membres de l\u2019AIP de tout l\u2019Idaho interviennent pour assurer une couverture de quarts de travail de 48 heures, \u00e0 compter du 9 juillet, pour la section locale 710, la section locale 2856 et la section locale 4045 de Northern Lakes, en Idaho.<\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>\u00ab Cette entreprise extraordinaire a \u00e9t\u00e9 rendue possible gr\u00e2ce \u00e0 la coordination coop\u00e9rative entre les pompiers professionnels de l\u2019Idaho (PFFI), l\u2019Association des chefs de pompiers de l\u2019Idaho et les dirigeants r\u00e9gionaux dont les efforts et le partenariat combin\u00e9s ont rendu le soutien possible \u00bb, a d\u00e9clar\u00e9 le vice-pr\u00e9sident de la PFFI, Matt Smith.  <\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>La couverture permettra aux membres des sections locales d\u2019assister aux fun\u00e9railles les jeudi et vendredi, les 10 et 11 juillet, et de maintenir une garde 24 heures sur 24 au salon fun\u00e9raire.  <\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>\u00ab Les organismes environnants se sont mobilis\u00e9s pour aider, et l\u2019\u00e9lan de soutien a \u00e9t\u00e9 exceptionnel et \u00e9norme \u00bb, a d\u00e9clar\u00e9 le secr\u00e9taire et tr\u00e9sorier de l\u2019IFFP, Curtis Smith. \u00ab Les demandes de b\u00e9n\u00e9volat ont \u00e9t\u00e9 remplies en 48 heures, et certains membres ont conduit jusqu\u2019\u00e0 10 heures pour aider. \u00bb   <\/p>\n<\/div>\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les organismes environnants se sont mobilis\u00e9s pour aider, et l\u2019effusion de soutien a \u00e9t\u00e9 exceptionnelle et \u00e9norme.<\/p><cite>Secr\u00e9taire\/tr\u00e9sorier des pompiers professionnels de l\u2019Idaho, Curtis Smith<\/cite><\/blockquote><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a040138da857&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a040138da857\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"98700\" src=\"https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FF-2-1024x576.jpg\" alt=\"\" class=\"wp-image-98700\" srcset=\"https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FF-2-1024x576.jpg 1024w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FF-2-300x169.jpg 300w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FF-2-768x432.jpg 768w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FF-2-240x135.jpg 240w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FF-2.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Photos de la section locale 876 de Spokane Valley, WA.<\/figcaption><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a040138dc2b9&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a040138dc2b9\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"98703\" src=\"https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FF-1024x768.jpg\" alt=\"\" class=\"wp-image-98703\" srcset=\"https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FF-1024x768.jpg 1024w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FF-300x225.jpg 300w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FF-768x576.jpg 768w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FF-240x180.jpg 240w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FF-1067x800.jpg 1067w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FF-1080x810.jpg 1080w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FF.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Photo de la procession de la section locale 876.<\/figcaption><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a040138dd90a&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a040138dd90a\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"98706\" src=\"https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FFs-3-1024x768.jpg\" alt=\"\" class=\"wp-image-98706\" srcset=\"https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FFs-3-1024x768.jpg 1024w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FFs-3-300x225.jpg 300w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FFs-3-768x576.jpg 768w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FFs-3-240x180.jpg 240w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FFs-3-1067x800.jpg 1067w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FFs-3-1080x810.jpg 1080w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/Spokane-Valley-FFs-3.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Photo de la procession de la section locale 876.<\/figcaption><\/figure>\n<\/figure>\n\n\n<div class=\"wp-block-paragraph \">\n<p>Des affili\u00e9s dans l\u2019\u00c9tat voisin de Washington, comme Spokane Valley, WA Local 876, sont \u00e9galement intervenus pour aider \u00e0 couvrir les quarts de travail, fournir du soutien par les pairs et effectuer des t\u00e2ches de garde d\u2019honneur.  <\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>\u00ab Nous avons fait tout un tas de d\u00e9briefings et aid\u00e9 avec une partie du soutien par les pairs \u00bb, a d\u00e9clar\u00e9 le pr\u00e9sident de la section locale 876, Ben James. \u00ab Nous avons envoy\u00e9 des \u00e9quipes lors de l\u2019\u00e9v\u00e9nement initial. J\u2019avais trois \u00e9quipes l\u00e0-bas lorsque l\u2019\u00e9v\u00e9nement s\u2019est produit. Ils se sont occup\u00e9s de nous lorsque nous avons eu notre d\u00e9c\u00e8s dans l\u2019exercice de ses fonctions impliquant le pompier de la section locale 876 <a href=\"https:\/\/lodd.iaff.org\/LODDProfile?ID=1213025\" target=\"_blank\" rel=\"noreferrer noopener\">\/ EMT Dan Patterson<\/a> il y a quelques ann\u00e9es, et ils sont aussi de la famille pour nous.     <\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>Plusieurs autres sections locales de la r\u00e9gion environnante, dont Northern Lakes, ID Local 4045 et Spokane, WA Local 29, ont particip\u00e9 \u00e0 l\u2019intervention initiale et participent aux efforts de soutien continus. \u00ab Ils faisaient aussi partie de la procession. Nous faisions partie de tout cela, nous aidions comme nous le pouvions \u00bb, a d\u00e9clar\u00e9 James.   <\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>\u00ab La r\u00e9ponse a \u00e9t\u00e9 assez ahurissante et la rapidit\u00e9 avec laquelle tout s\u2019est mis en place. L\u2019IFFP a organis\u00e9 cet effort consid\u00e9rable pour s\u2019assurer qu\u2019il y avait une couverture afin que les intervenants puissent assister aux deux services \u00bb, a d\u00e9clar\u00e9 le pr\u00e9sident de la section locale 4045, Jarrod Pitts. \u00ab Pour moi, cela montre vraiment pourquoi les pompiers sont membres de la fraternit\u00e9 de l\u2019AIP. Ils reviennent de fa\u00e7on formidable, encore et encore. <\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>Dans toute la r\u00e9gion, les dirigeants de l\u2019AIP ont exprim\u00e9 leur profonde gratitude \u00e0 leurs communaut\u00e9s pour le soutien manifest\u00e9 face \u00e0 la trag\u00e9die.  <\/p>\n<\/div>\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a040138e0df7&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a040138e0df7\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"98709\" src=\"https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/86026c58-ca2c-4355-8a50-b05c30a9f2cc-1024x768.jpeg\" alt=\"\" class=\"wp-image-98709\" srcset=\"https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/86026c58-ca2c-4355-8a50-b05c30a9f2cc-1024x768.jpeg 1024w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/86026c58-ca2c-4355-8a50-b05c30a9f2cc-300x225.jpeg 300w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/86026c58-ca2c-4355-8a50-b05c30a9f2cc-768x576.jpeg 768w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/86026c58-ca2c-4355-8a50-b05c30a9f2cc-240x180.jpeg 240w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/86026c58-ca2c-4355-8a50-b05c30a9f2cc-1067x800.jpeg 1067w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/86026c58-ca2c-4355-8a50-b05c30a9f2cc-1080x810.jpeg 1080w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/86026c58-ca2c-4355-8a50-b05c30a9f2cc.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Membres de la garde d\u2019honneur \u00e0 la procession.<\/figcaption><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a040138e2188&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a040138e2188\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"98712\" src=\"https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/132024ef-578f-453b-a518-2e17514b73a1-1024x768.jpeg\" alt=\"\" class=\"wp-image-98712\" srcset=\"https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/132024ef-578f-453b-a518-2e17514b73a1-1024x768.jpeg 1024w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/132024ef-578f-453b-a518-2e17514b73a1-300x225.jpeg 300w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/132024ef-578f-453b-a518-2e17514b73a1-768x576.jpeg 768w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/132024ef-578f-453b-a518-2e17514b73a1-240x180.jpeg 240w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/132024ef-578f-453b-a518-2e17514b73a1-1067x800.jpeg 1067w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/132024ef-578f-453b-a518-2e17514b73a1-1080x810.jpeg 1080w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/132024ef-578f-453b-a518-2e17514b73a1.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Des camions de pompiers se sont align\u00e9s lors de la procession.<\/figcaption><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a040138e3c76&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a040138e3c76\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"98718\" src=\"https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/d0886672-2511-40c8-9e59-8eefa0f59ae2-1024x768.jpeg\" alt=\"\" class=\"wp-image-98718\" srcset=\"https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/d0886672-2511-40c8-9e59-8eefa0f59ae2-1024x768.jpeg 1024w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/d0886672-2511-40c8-9e59-8eefa0f59ae2-300x225.jpeg 300w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/d0886672-2511-40c8-9e59-8eefa0f59ae2-768x576.jpeg 768w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/d0886672-2511-40c8-9e59-8eefa0f59ae2-240x180.jpeg 240w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/d0886672-2511-40c8-9e59-8eefa0f59ae2-1067x800.jpeg 1067w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/d0886672-2511-40c8-9e59-8eefa0f59ae2-1080x810.jpeg 1080w, https:\/\/www.iaff.org\/wp-content\/uploads\/2025\/07\/d0886672-2511-40c8-9e59-8eefa0f59ae2.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Des membres de la garde d\u2019honneur \u00e0 la procession \u00e0 Coeur d\u2019Alene.  <\/figcaption><\/figure>\n<\/figure>\n\n\n<div class=\"wp-block-paragraph \">\n<p>\u00ab Au nom des 1 500 membres des pompiers professionnels de l\u2019Idaho, nous demandons \u00e0 nos communaut\u00e9s \u00e0 travers l\u2019\u00c9tat et le pays d\u2019\u00eatre solidaires des familles et des services touch\u00e9s \u00bb, a d\u00e9clar\u00e9 le pr\u00e9sident de la PFFI, Rob Shoplock. \u00ab Nos membres continueront de r\u00e9pondre \u00e0 l\u2019appel \u2013 aujourd\u2019hui, demain et tous les jours \u00e0 l\u2019avenir. Nous sommes \u2013 maintenant et toujours \u2013 aux c\u00f4t\u00e9s de nos fr\u00e8res tomb\u00e9s au combat des sections locales 710 et 2856 et de leurs familles.   <\/p>\n<\/div>\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Nos membres continueront de r\u00e9pondre \u00e0 l\u2019appel \u2013 aujourd\u2019hui, demain et tous les jours \u00e0 l\u2019avenir.<\/p><cite>Le pr\u00e9sident des pompiers professionnels de l\u2019Idaho Rob Shoplock<\/cite><\/blockquote><\/figure>\n\n\n<div class=\"wp-block-paragraph \">\n<p>Le vice-pr\u00e9sident du 7e district, Ricky Walsh, a \u00e9galement soulign\u00e9 la force et l\u2019unit\u00e9 au sein de la communaut\u00e9 l\u2019AIP .  <\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>\u00ab Le 7e district est une communaut\u00e9 tiss\u00e9e serr\u00e9e au sein de la grande l\u2019AIP \u00bb, a d\u00e9clar\u00e9 Walsh. \u00ab Nous avons un leadership solide qui travaille avec les ressources envoy\u00e9es par le pr\u00e9sident g\u00e9n\u00e9ral Kelly pour s\u2019assurer que nos soldats tomb\u00e9s au combat sont honor\u00e9s comme il se doit, que leurs familles sont prises en charge et que les besoins de nos membres des sections locales 710, 2856 et 4045 sont satisfaits. Nous ne laisserons personne de c\u00f4t\u00e9.   <\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>Les affili\u00e9s de l\u2019Idaho qui aident comprennent Northern Lakes, Idaho Local 4045, Boise, Idaho Local 149, Pocatello, Idaho Local 187, Nampa, Idaho Local 804, Twin Falls, Idaho Local 1556, Idaho Falls, Idaho Local 1565, Lewiston, Idaho Local 1773, Caldwell, Idaho Local 1821, W. Shoshone County, Idaho Local 2034, Meridian, Idaho Local 2311, Blackfoot, Idaho Local 4454, Eagle, Idaho Local 4553,  Middleton, section locale 4626 de l\u2019Idaho, Worley, section locale 5005 de l\u2019Idaho, comt\u00e9 de Shoshone, section locale 5310 de l\u2019Idaho, et Laboratoire national de l\u2019Idaho, section locale I-83 de l\u2019Idaho.<\/p>\n<\/div>\n<\/div><\/section>\n","protected":false},"featured_media":98716,"menu_order":0,"template":"","tags":[189,112],"class_list":["post-98732","news","type-news","status-publish","has-post-thumbnail","hentry","tag-lodd-fr-ca-2","tag-redonner"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/news\/98732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":0,"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/news\/98732\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/media\/98716"}],"wp:attachment":[{"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/media?parent=98732"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/tags?post=98732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}