{"id":122475,"date":"2026-03-19T14:28:44","date_gmt":"2026-03-19T18:28:44","guid":{"rendered":"https:\/\/www.iaff.org\/news\/les-pompiers-militent-pour-une-action-nationale-contre-les-incendies-de-batteries-lithium-ion-au-canada\/"},"modified":"2026-03-19T14:33:22","modified_gmt":"2026-03-19T18:33:22","slug":"les-pompiers-militent-pour-une-action-nationale-contre-les-incendies-de-batteries-lithium-ion-au-canada","status":"publish","type":"news","link":"https:\/\/www.iaff.org\/fr-ca\/news\/les-pompiers-militent-pour-une-action-nationale-contre-les-incendies-de-batteries-lithium-ion-au-canada\/","title":{"rendered":"Les pompiers militent pour une action nationale contre les incendies de batteries lithium-ion au Canada"},"content":{"rendered":"<section\n\t class=\"page-blocks iaff-page-blocks align wp-block-acf-page-blocks\" id=\"page-blocks_block_a62a3a0ef4af5d5999301fed5effd2ae\">\n\t<div class=\"acf-innerblocks-container\">\n<div class=\"wp-block-paragraph \">\n<p>Les incendies de batteries lithium-ion s\u2019intensifient partout au Canada, exposant les pompiers \u00e0 des conditions plus dangereuses et \u00e0 de nouveaux risques au travail \u2013 et stimulant une pouss\u00e9e nationale pour agir.<\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>En juillet 2025, un homme de la Colombie-Britannique a film\u00e9 <a href=\"https:\/\/www.youtube.com\/shorts\/Mr35GEQskTE\" target=\"_blank\" rel=\"noopener\">son<\/a> v\u00e9lo \u00e9lectrique prenant des flammes peu apr\u00e8s l\u2019avoir emmen\u00e9 pour une sortie de routine, l\u2019un des nombreux incidents li\u00e9s aux batteries lithium-ion utilis\u00e9es dans les v\u00e9hicules et l\u2019\u00e9lectronique de tous les jours. Ces feux br\u00fblent plus fort et se comportent de fa\u00e7on impr\u00e9visible sur le terrain, cr\u00e9ant de nouveaux risques pour les pompiers. <\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>La menace croissante a pouss\u00e9 la pr\u00e9sidente de la section locale 18 de Vancouver, Katrina Davison, \u00e0 appeler \u00e0 une strat\u00e9gie nationale incluant un meilleur suivi et une meilleure r\u00e9glementation des sources d\u2019\u00e9nergie d\u00e9sormais omnipr\u00e9sentes.<\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>La question est ajout\u00e9e \u00e0 l\u2019ordre du jour l\u00e9gislatif de l\u2019AIP (IAFF) pour la <a href=\"https:\/\/www.iaff.org\/fr-ca\/conference-legislative-canadienne\/\"><sup>33e<\/sup> Conf\u00e9rence l\u00e9gislative canadienne, du 19 au 21 avril \u00e0 Ottawa<\/a>.<\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>\u00ab Cette initiative am\u00e9liorerait la s\u00e9curit\u00e9 des pompiers lors d\u2019incendies de batteries au lithium, soutiendrait la protection de la sant\u00e9 des pompiers fond\u00e9e sur des donn\u00e9es probantes, renforcerait la pr\u00e9paration du Canada face aux risques \u00e9mergents d\u2019incendie et assurerait l\u2019int\u00e9gration s\u00e9curitaire des technologies d\u2019\u00e9lectrification dans les communaut\u00e9s \u00e0 travers le pays \u00bb, a d\u00e9clar\u00e9 Davison. \u00ab Ces r\u00e9sultats renforceraient collectivement \u00e0 la fois le service d\u2019incendie et le public qu\u2019il sert. \u00bb <\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>Les donn\u00e9es des services de secours incendie de Vancouver montrent que les incendies de batteries rechargeables ont presque doubl\u00e9 entre 2021 et 2024, passant de 29 \u00e0 53 incidents.<\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>D\u2019autres grandes villes rapportent des tendances similaires. Les services d\u2019incendie de Toronto ont enregistr\u00e9 une augmentation de 591% entre 2020 et 2024, tandis que le Service d\u2019incendie de Montr\u00e9al a enregistr\u00e9 une hausse de 195% depuis qu\u2019il a commenc\u00e9 \u00e0 suivre les incidents en 2022. <\/p>\n<\/div>\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Cette initiative am\u00e9liorerait la s\u00e9curit\u00e9 des pompiers lors d\u2019incendies de batteries au lithium, soutiendrait les protections sanitaires fond\u00e9es sur des donn\u00e9es probantes, renforcerait la pr\u00e9paration du Canada face aux risques \u00e9mergents d\u2019incendie et assurerait l\u2019int\u00e9gration s\u00e9curitaire des technologies d\u2019\u00e9lectrification dans les communaut\u00e9s \u00e0 travers le pays.<\/p><cite>Pr\u00e9sidente de la section locale 18 de Vancouver, Katrina Davison,<\/cite><\/blockquote><\/figure>\n\n\n<div class=\"wp-block-paragraph \">\n<p>Les modifications non autoris\u00e9es, la surcharge, l\u2019\u00e9limination inad\u00e9quate et les dommages physiques augmentent consid\u00e9rablement le risque de fuite thermique \u2013 une r\u00e9action en cha\u00eene dangereuse \u00e0 l\u2019int\u00e9rieur de la batterie qui m\u00e8ne \u00e0 un incendie ou une explosion.<\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>Davison a indiqu\u00e9 que ces incendies exposent les pompiers et autres intervenants d\u2019urgence aux gaz toxiques et soul\u00e8vent des questions sur les normes de formation, les \u00e9quipements de protection, et si les codes du b\u00e2timent refl\u00e8tent la pr\u00e9sence croissante d\u2019appareils lithium-ion dans les maisons et les immeubles r\u00e9sidentiels \u00e0 logements multiples.<\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>Lors de la Conf\u00e9rence l\u00e9gislative canadienne de l\u2019AIP (IAFF), les d\u00e9l\u00e9gu\u00e9s demanderont au gouvernement f\u00e9d\u00e9ral d\u2019\u00e9tablir une Initiative nationale de s\u00e9curit\u00e9 des pompiers \u00e0 batteries lithium-ion \u2013 un programme coordonn\u00e9 pour suivre les incidents, \u00e9tudier les expositions des pompiers, standardiser la formation, mettre \u00e0 jour les codes du b\u00e2timent et financer l\u2019\u00e9quipement et la technologie de protection.<\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph \">\n<p>Les d\u00e9l\u00e9gu\u00e9s feront \u00e9galement du lobbying pour <a href=\"https:\/\/www.iaff.org\/fr-ca\/news\/une-nouvelle-priorite-legislative-emerge-a-lapproche-de-la-33e-conference-legislative-canadienne\/\">l\u2019indexation du Programme de subventions comm\u00e9moratives pour les premiers r\u00e9pondants et le renforcement des r\u00e8glements qui r\u00e9gissent le sauvetage et la lutte contre les incendies a\u00e9roportuaires<\/a> au Canada.<\/p>\n<\/div>\n<\/div><\/section>\n","protected":false},"featured_media":122471,"menu_order":0,"template":"","tags":[62,115,186],"class_list":["post-122475","news","type-news","status-publish","has-post-thumbnail","hentry","tag-canada-fr-ca","tag-legislation-canadienne","tag-securite-au-travail-fr-ca"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/news\/122475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":2,"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/news\/122475\/revisions"}],"predecessor-version":[{"id":122477,"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/news\/122475\/revisions\/122477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/media\/122471"}],"wp:attachment":[{"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/media?parent=122475"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iaff.org\/fr-ca\/wp-json\/wp\/v2\/tags?post=122475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}